{"id":1781,"date":"2023-12-15T16:39:08","date_gmt":"2023-12-15T19:39:08","guid":{"rendered":"https:\/\/ampla.ind.br\/?post_type=produto&#038;p=1781"},"modified":"2024-01-22T10:45:47","modified_gmt":"2024-01-22T13:45:47","slug":"plansifter","status":"publish","type":"produto","link":"https:\/\/ampla.ind.br\/es\/produto\/plansifter\/","title":{"rendered":"Plansifter"},"content":{"rendered":"\t\t\n\t\t<section class=\"content primary-product\">\n\n\t    \t<div class=\"container\">\n\t    \t\t<div class=\"row\">\n\n\t    \t\t\t<div class=\"col-lg-5 mb-5\">\n\t    \t\t\t\t\n\t    \t\t\t\t<div class=\"page-header pe-lg-5\">\n\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"page-subtitle mb-4\">Plansifter<\/h2>\n\t\t\n\t\t\t\t\t\t\t\t<h3 class=\"page-subtitle mb-4\">Optimize la criba y clasificaci\u00f3n de productos triturados con nuestro Plansifter. <\/h3>\n\t\n\t\t\t\t\t\t\t\t<p>Desarrollado para el cribado y clasificaci\u00f3n de productos provenientes de la trituraci\u00f3n, como harina y productos intermedios de molienda, realizando de manera efectiva la clasificaci\u00f3n granulom\u00e9trica de los productos.<\/p>\n\t\t\n\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t    \t\t\t<\/div>\n\n\t\t    \t\t\t<div class=\"col-lg-6 slide-product offset-lg-1\">\n\t    \t\t\t\t\n\t    \t\t\t\t<span class=\"sombra\"><\/span>\n\n\t\t    \t\t\t<div class=\"swiper gal\">\n\n\t\t\t\t\t\t    <div class=\"swiper-wrapper\">\n\t\t\t\t\t\t    \n\t\t\t\t\t\t\t\t\t  <div class=\"swiper-slide\">\n\t\t\t\t\t\t      \t<img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Plansifter.png\" alt=\"Plansifter\">\n\t\t\t\t\t\t      <\/div>\n\t\t\t\t\t\t\t\t      \n\t\t\t\t\t\t    <\/div>\n\n\t\t\t\t\t\t    <div class=\"navgation-slider\">\n\t\t\t\t\t\t\t    <div class=\"slide-product-next swiper-button-next\"><\/div>\n\t\t    \t\t\t\t\t<div class=\"slide-product-prev swiper-button-prev\"><\/div>\n\t\t    \t\t\t\t\t<div class=\"slide-product-pagination swiper-pagination\"><\/div>\n\t\t    \t\t\t\t<\/div>\n\n\t\t    \t\t\t<\/div>\n\t\t    \t\t<\/div>\n\t\n\t    \t\t<\/div>\n\t    \t<\/div>\n\n\t    <\/section>\n\n\n\t\t  <section class=\"services\">\n\t\t    <div class=\"container\">\n\t\t      <div class=\"row\">\n\n\t\t\t\t<div class=\"col-md-5 pr-md-5\">\n\t\t\t\t  \n\t\t\t\t\t  <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Prancheta-1@4x-e1705606817567.png\" title=\"Prancheta 1@4x\" class=\"mb-4\">\n\t\t\n\t\t\t\t\t  <h2 class=\"services__title graphism-title\">Equipos y soluciones completas para la Industria<\/h2>\n\t\t\n\t\t        <\/div>\n\n\t\t\t        <div class=\"col-md-6 offset-lg-1\">\n\t\t          <div id=\"servicesAccordion\" role=\"tablist\" aria-multiselectable=\"true\">\n\t\t          \n\t\t\t\t\t\t\t<div class=\"services-accordion\">\n\t\t\t\t\t\t<div class=\"services-accordion-header\" id=\"brand1\">\n\t\t\t\t\t\t  <a data-bs-toggle=\"collapse\" class=\"accordion-toggle\" data-parent=\"#servicesAccordion\" href=\"#brand-1\" aria-expanded=\"true\" aria-controls=\"brand-1\">\n\t\t\t\t\t\t\t<div class=\"open-detail float-right\">\n\t\t\t\t\t\t\t  <i class=\"fa fa-plus\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t  <i class=\"fa fa-minus\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<h5 class=\"accordion__title\">Principales caracter\u00edsticas del equipo:<\/h5>\n\t\t\t\t\t\t  <\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div id=\"brand-1\" class=\"collapse in show\" aria-labelledby=\"brand-1\">\n\t\t\t\t\t\t  <div class=\"services-content\">\n\t\t\t\t\t\t\t<p><ul>\n<li>Alta eficiencia<\/li>\n<li>Alta precisi\u00f3n<\/li>\n<li>Mayor higiene en el proceso<\/li>\n<li>Clasificaci\u00f3n seg\u00fan la granulometr\u00eda<\/li>\n<li>Separaci\u00f3n de materiales<\/li>\n<li>Bajo mantenimiento<\/li>\n<li>F\u00e1cil limpieza<\/li>\n<li>Sellado del producto en el interior del equipo.<\/li>\n<\/ul>\n<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\n\t\t          <\/div>\n\t\t        <\/div>\n\t\t\t      \n\t\t      <\/div>\n\t\t    <\/div>\n\t\t  <\/section>\n\n\n  <section class=\"products products__list\">\n    <div class=\"container\">\n      \n      <div class=\"row align-items-center justify-content-center filter\">\n        \n\n        <div class=\"text-center col page-subtitle\">\n\t\t\t<h2>Productos similares<\/h2>\n\t\t<\/div>\n\n        \n      <\/div>\n      \n      \n      <div class=\"products-list d-none d-md-block\">\n        <div class=\"swiper products-slider\">\n          <div class=\"swiper-wrapper\">\n          \n\t\t\t\t\t<div class=\"swiper-slide\">\n                  <div class=\"card\">\n                    <div class=\"row no-gutters\">\n                      <div class=\"col-4 col-md-12\">\n                                <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Valvula-Registro-Gaveta-Pneumatico.png\" alt=\"V\u00e1lvula Registro Gaveta Pneum\u00e1tico\" class=\"card-img-top\">\n                              <\/div>\n                      <div class=\"col-8 col-md-12\">\n                        <div class=\"card-body p-0 p-md-3 text-left text-md-center\">\n                                  <span class=\"badge badge-pill badge-primary ml-2 ml-md-0\">Linha Leve<\/span>\n                          \n                          <h5 class=\"card-title\">\n                            <a href=\"https:\/\/ampla.ind.br\/es\/produto\/valvula-registro-gaveta-pneumatico\/\" title=\"Ver producto\">V\u00e1lvula Registro Gaveta Pneum\u00e1tico<\/a>\n                          <\/h5>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n                  <\/div>\n                <\/div>\n\t\t\t\t\t<div class=\"swiper-slide\">\n                  <div class=\"card\">\n                    <div class=\"row no-gutters\">\n                      <div class=\"col-4 col-md-12\">\n                                <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Valvula-Registro-Gaveta-Manual.png\" alt=\"V\u00e1lvula Registro Gaveta Manual\" class=\"card-img-top\">\n                              <\/div>\n                      <div class=\"col-8 col-md-12\">\n                        <div class=\"card-body p-0 p-md-3 text-left text-md-center\">\n                                  <span class=\"badge badge-pill badge-primary ml-2 ml-md-0\">Linha Leve<\/span>\n                          \n                          <h5 class=\"card-title\">\n                            <a href=\"https:\/\/ampla.ind.br\/es\/produto\/valvula-registro-gaveta-manual\/\" title=\"Ver producto\">V\u00e1lvula Registro Gaveta Manual<\/a>\n                          <\/h5>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n                  <\/div>\n                <\/div>\n\t\t\t\t\t<div class=\"swiper-slide\">\n                  <div class=\"card\">\n                    <div class=\"row no-gutters\">\n                      <div class=\"col-4 col-md-12\">\n                                <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Valvula-Rotativa-Horizontal.png\" alt=\"V\u00e1lvula Rotativa Horizontal\" class=\"card-img-top\">\n                              <\/div>\n                      <div class=\"col-8 col-md-12\">\n                        <div class=\"card-body p-0 p-md-3 text-left text-md-center\">\n                                  <span class=\"badge badge-pill badge-primary ml-2 ml-md-0\">Linha Leve<\/span>\n                          \n                          <h5 class=\"card-title\">\n                            <a href=\"https:\/\/ampla.ind.br\/es\/produto\/valvula-rotativa-horizontal\/\" title=\"Ver producto\">V\u00e1lvula Rotativa Horizontal<\/a>\n                          <\/h5>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n                  <\/div>\n                <\/div>\n\t\t\t\t\t<div class=\"swiper-slide\">\n                  <div class=\"card\">\n                    <div class=\"row no-gutters\">\n                      <div class=\"col-4 col-md-12\">\n                                <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Plansifter.png\" alt=\"Plansifter\" class=\"card-img-top\">\n                              <\/div>\n                      <div class=\"col-8 col-md-12\">\n                        <div class=\"card-body p-0 p-md-3 text-left text-md-center\">\n                                  <span class=\"badge badge-pill badge-primary ml-2 ml-md-0\">Linha Leve<\/span>\n                          \n                          <h5 class=\"card-title\">\n                            <a href=\"https:\/\/ampla.ind.br\/es\/produto\/plansifter\/\" title=\"Ver producto\">Plansifter<\/a>\n                          <\/h5>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n                  <\/div>\n                <\/div>\n\t\t\t\t\t<div class=\"swiper-slide\">\n                  <div class=\"card\">\n                    <div class=\"row no-gutters\">\n                      <div class=\"col-4 col-md-12\">\n                                <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Valvula-Diversora-Pneumatica.png\" alt=\"V\u00e1lvula Diversora Pneum\u00e1tica\" class=\"card-img-top\">\n                              <\/div>\n                      <div class=\"col-8 col-md-12\">\n                        <div class=\"card-body p-0 p-md-3 text-left text-md-center\">\n                                  <span class=\"badge badge-pill badge-primary ml-2 ml-md-0\">Linha Leve<\/span>\n                          \n                          <h5 class=\"card-title\">\n                            <a href=\"https:\/\/ampla.ind.br\/es\/produto\/valvula-diversora-pneumatica\/\" title=\"Ver producto\">V\u00e1lvula Diversora Pneum\u00e1tica<\/a>\n                          <\/h5>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n                  <\/div>\n                <\/div>\n\t                \n            <\/div>\n        <\/div>\n        <div class=\"product-prev swiper-button-prev d-none d-md-block\"><\/div>\n        <div class=\"product-next swiper-button-next d-none d-md-block\"><\/div>\n      <\/div>\n      \n      <div class=\"product-swiper-pagination text-center d-none d-lg-block\"><\/div>\n      \n      \n      <div class=\"products-list products-list-mobile d-md-none\">\n          \n\t\t\t<div class=\"card\">\n            <div class=\"row no-gutters\">\n                <div class=\"col-4 col-md-12\">\n        \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/themes\/ampla_2023\/assets\/images\/default.png\" alt=\"Pain\u00e9is El\u00e9tricos\" class=\"card-img-top\">\n                        <\/div>\n                <div class=\"col-8 col-md-12\">\n                    <div class=\"card-body p-0 p-md-3 text-left text-md-center\">\n                                <span class=\"badge badge-pill badge-primary ml-2 ml-md-0\">Linha Leve<\/span>\n                          \n                        <h5 class=\"card-title\">\n                            <a href=\"https:\/\/ampla.ind.br\/es\/produto\/paineis-eletricos\/\" title=\"Ver producto\">Pain\u00e9is El\u00e9tricos<\/a>\n                        <\/h5>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\t\t\t<div class=\"card\">\n            <div class=\"row no-gutters\">\n                <div class=\"col-4 col-md-12\">\n                            <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Transportador-Tubular-de-correntes.png\" alt=\"Transportador Tubular de Corrente\" class=\"card-img-top\">\n                        <\/div>\n                <div class=\"col-8 col-md-12\">\n                    <div class=\"card-body p-0 p-md-3 text-left text-md-center\">\n                                <span class=\"badge badge-pill badge-primary ml-2 ml-md-0\">Sistemas e Tecnologias de processo<\/span>\n                          \n                        <h5 class=\"card-title\">\n                            <a href=\"https:\/\/ampla.ind.br\/es\/produto\/transportador-tubular-de-corrente\/\" title=\"Ver producto\">Transportador Tubular de Corrente<\/a>\n                        <\/h5>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\t\t\t<div class=\"card\">\n            <div class=\"row no-gutters\">\n                <div class=\"col-4 col-md-12\">\n                            <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/transporte-pneumatico-fase-densa.png\" alt=\"Transportador Pneum\u00e1tico de Fase Densa\" class=\"card-img-top\">\n                        <\/div>\n                <div class=\"col-8 col-md-12\">\n                    <div class=\"card-body p-0 p-md-3 text-left text-md-center\">\n                                <span class=\"badge badge-pill badge-primary ml-2 ml-md-0\">Sistemas e Tecnologias de processo<\/span>\n                          \n                        <h5 class=\"card-title\">\n                            <a href=\"https:\/\/ampla.ind.br\/es\/produto\/transportador-pneumatico-de-fase-densa\/\" title=\"Ver producto\">Transportador Pneum\u00e1tico de Fase Densa<\/a>\n                        <\/h5>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\t\t\n\t\t\t<div class=\"product-pagination\">\n\t\t\t<a href=\"#\" class=\"current d-none\">1<\/a>\n\t\t\t<a href=\"#\" class=\"btn btn-outline-primary next\">Carga m\u00e1s<\/a>\n\t\t<\/div>\n\t\t\n      <\/div>\n  \n\n\t<\/div>\n  <\/section>\n\n\n  <section class=\"segments \">\n    <div class=\"container\">\n      <div class=\"row justify-content-center justify-content-md-start\">\n        \n        <div class=\"col-auto col-md-12\">\n          <h3 class=\"segments__title graphism-title\">\n            <div class=\"d-none d-md-block\">\n              <span class=\"graphism graphism-left\"><\/span>\n            <\/div>\n            Segmentos<\/h3>\n        <\/div>\n        \n        \n      <\/div>\n      \n      \n      <div class=\"row justify-content-center\">\n        <div class=\"swiper segmentos-slider swiper-initialized swiper-horizontal swiper-backface-hidden\">\n          <div class=\"swiper-wrapper\" id=\"swiper-wrapper-184cd441ce64f10f8\" aria-live=\"polite\">\n              \n    \t\n\t\t\t  <div class=\"swiper-slide\" role=\"segments\">\n                <div class=\"cards-wrapper\">\n                  <div class=\"cards-segments\">\n                    <div class=\"card card-segment card-segment-front\">\n                      <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/10\/segmento-biodiesel-demo.png\" alt=\"imagen de segmento Energ\u00eda: Biodiesel y Etanol\">\n                      <div class=\"card-body card-img-overlay text-center\">\n                        <h5 class=\"card-title\">\n                          Energ\u00eda: Biodiesel y Etanol<\/h5>\n                      <\/div>\n                    <\/div>\n                    <div class=\"card card-segment card-segment-back\">\n                      <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/10\/segmento-biodiesel-demo.png\" alt=\"imagen de segmento Energ\u00eda: Biodiesel y Etanol\">\n                      <div class=\"card-body card-img-overlay text-center\">\n                        <h5 class=\"card-title\">\n                          Energ\u00eda: Biodiesel y Etanol<span class=\"graphism graphism-bottom\"><\/span>\n                        <\/h5>\n                        <div class=\"card-text\"><\/div>\n                        <div class=\"card-footer border-0\">\n                            <a href=\"https:\/\/ampla.ind.br\/es\/segmento\/proyectos-electricos\/\" title=\"Ver segmento Energ\u00eda: Biodiesel y Etanol\" class=\"btn\">Ver productos<\/a>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n                  <\/div>\n                <\/div>\n              <\/div>\n\t\n\t\t\n\t\t\t  <div class=\"swiper-slide\" role=\"segments\">\n                <div class=\"cards-wrapper\">\n                  <div class=\"cards-segments\">\n                    <div class=\"card card-segment card-segment-front\">\n                      <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/ampla-segmento-oleos-biodiesel.png\" alt=\"imagen de segmento Aceites Vegetales\">\n                      <div class=\"card-body card-img-overlay text-center\">\n                        <h5 class=\"card-title\">\n                          Aceites Vegetales<\/h5>\n                      <\/div>\n                    <\/div>\n                    <div class=\"card card-segment card-segment-back\">\n                      <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/ampla-segmento-oleos-biodiesel.png\" alt=\"imagen de segmento Aceites Vegetales\">\n                      <div class=\"card-body card-img-overlay text-center\">\n                        <h5 class=\"card-title\">\n                          Aceites Vegetales<span class=\"graphism graphism-bottom\"><\/span>\n                        <\/h5>\n                        <div class=\"card-text\"><\/div>\n                        <div class=\"card-footer border-0\">\n                            <a href=\"https:\/\/ampla.ind.br\/es\/segmento\/industria-de-aceites-vegetales-y-biodiesel\/\" title=\"Ver segmento Aceites Vegetales\" class=\"btn\">Ver productos<\/a>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n                  <\/div>\n                <\/div>\n              <\/div>\n\t\n\t\t\n\t\t\t  <div class=\"swiper-slide\" role=\"segments\">\n                <div class=\"cards-wrapper\">\n                  <div class=\"cards-segments\">\n                    <div class=\"card card-segment card-segment-front\">\n                      <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/ampla-segmento-projetos-eletricos.png\" alt=\"imagen de segmento Automatizaci\u00f3n\">\n                      <div class=\"card-body card-img-overlay text-center\">\n                        <h5 class=\"card-title\">\n                          Automatizaci\u00f3n<\/h5>\n                      <\/div>\n                    <\/div>\n                    <div class=\"card card-segment card-segment-back\">\n                      <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/ampla-segmento-projetos-eletricos.png\" alt=\"imagen de segmento Automatizaci\u00f3n\">\n                      <div class=\"card-body card-img-overlay text-center\">\n                        <h5 class=\"card-title\">\n                          Automatizaci\u00f3n<span class=\"graphism graphism-bottom\"><\/span>\n                        <\/h5>\n                        <div class=\"card-text\"><\/div>\n                        <div class=\"card-footer border-0\">\n                            <a href=\"https:\/\/ampla.ind.br\/es\/segmento\/automatizacion\/\" title=\"Ver segmento Automatizaci\u00f3n\" class=\"btn\">Ver productos<\/a>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n                  <\/div>\n                <\/div>\n              <\/div>\n\t\n\t\t\n\t\t\t  <div class=\"swiper-slide\" role=\"segments\">\n                <div class=\"cards-wrapper\">\n                  <div class=\"cards-segments\">\n                    <div class=\"card card-segment card-segment-front\">\n                      <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/ampla-segmento-alimentacao.png\" alt=\"imagen de segmento Alimentos\">\n                      <div class=\"card-body card-img-overlay text-center\">\n                        <h5 class=\"card-title\">\n                          Alimentos<\/h5>\n                      <\/div>\n                    <\/div>\n                    <div class=\"card card-segment card-segment-back\">\n                      <img decoding=\"async\" src=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/ampla-segmento-alimentacao.png\" alt=\"imagen de segmento Alimentos\">\n                      <div class=\"card-body card-img-overlay text-center\">\n                        <h5 class=\"card-title\">\n                          Alimentos<span class=\"graphism graphism-bottom\"><\/span>\n                        <\/h5>\n                        <div class=\"card-text\"><\/div>\n                        <div class=\"card-footer border-0\">\n                            <a href=\"https:\/\/ampla.ind.br\/es\/segmento\/alimentos\/\" title=\"Ver segmento Alimentos\" class=\"btn\">Ver productos<\/a>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n                  <\/div>\n                <\/div>\n              <\/div>\n\t\n\t              \n            <\/div>\n        <span class=\"swiper-notification\" aria-live=\"assertive\" aria-atomic=\"true\"><\/span><\/div>\n      <\/div>\n      \n\n    <\/div>\n  <\/section>","protected":false},"featured_media":524,"template":"","linha":[],"class_list":["post-1781","produto","type-produto","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plansifter - Ampla Performance Industrial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ampla.ind.br\/produto\/plansifter\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plansifter - Ampla Performance Industrial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ampla.ind.br\/produto\/plansifter\/\" \/>\n<meta property=\"og:site_name\" content=\"Ampla Performance Industrial\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-22T13:45:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Plansifter.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ampla.ind.br\\\/produto\\\/plansifter\\\/\",\"url\":\"https:\\\/\\\/ampla.ind.br\\\/produto\\\/plansifter\\\/\",\"name\":\"Plansifter - Ampla Performance Industrial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ampla.ind.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ampla.ind.br\\\/produto\\\/plansifter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ampla.ind.br\\\/produto\\\/plansifter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ampla.ind.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Plansifter.png\",\"datePublished\":\"2023-12-15T19:39:08+00:00\",\"dateModified\":\"2024-01-22T13:45:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ampla.ind.br\\\/produto\\\/plansifter\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ampla.ind.br\\\/produto\\\/plansifter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ampla.ind.br\\\/produto\\\/plansifter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ampla.ind.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Plansifter.png\",\"contentUrl\":\"https:\\\/\\\/ampla.ind.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Plansifter.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ampla.ind.br\\\/produto\\\/plansifter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ampla.ind.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plansifter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ampla.ind.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ampla.ind.br\\\/en\\\/\",\"name\":\"Ampla Performance Industrial\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ampla.ind.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plansifter - Ampla Performance Industrial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ampla.ind.br\/produto\/plansifter\/","og_locale":"es_ES","og_type":"article","og_title":"Plansifter - Ampla Performance Industrial","og_url":"https:\/\/ampla.ind.br\/produto\/plansifter\/","og_site_name":"Ampla Performance Industrial","article_modified_time":"2024-01-22T13:45:47+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Plansifter.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ampla.ind.br\/produto\/plansifter\/","url":"https:\/\/ampla.ind.br\/produto\/plansifter\/","name":"Plansifter - Ampla Performance Industrial","isPartOf":{"@id":"https:\/\/ampla.ind.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ampla.ind.br\/produto\/plansifter\/#primaryimage"},"image":{"@id":"https:\/\/ampla.ind.br\/produto\/plansifter\/#primaryimage"},"thumbnailUrl":"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Plansifter.png","datePublished":"2023-12-15T19:39:08+00:00","dateModified":"2024-01-22T13:45:47+00:00","breadcrumb":{"@id":"https:\/\/ampla.ind.br\/produto\/plansifter\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ampla.ind.br\/produto\/plansifter\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ampla.ind.br\/produto\/plansifter\/#primaryimage","url":"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Plansifter.png","contentUrl":"https:\/\/ampla.ind.br\/wp-content\/uploads\/2023\/12\/Plansifter.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/ampla.ind.br\/produto\/plansifter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ampla.ind.br\/es\/"},{"@type":"ListItem","position":2,"name":"Plansifter"}]},{"@type":"WebSite","@id":"https:\/\/ampla.ind.br\/en\/#website","url":"https:\/\/ampla.ind.br\/en\/","name":"Ampla Performance Industrial","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ampla.ind.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/ampla.ind.br\/es\/wp-json\/wp\/v2\/produto\/1781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ampla.ind.br\/es\/wp-json\/wp\/v2\/produto"}],"about":[{"href":"https:\/\/ampla.ind.br\/es\/wp-json\/wp\/v2\/types\/produto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ampla.ind.br\/es\/wp-json\/wp\/v2\/media\/524"}],"wp:attachment":[{"href":"https:\/\/ampla.ind.br\/es\/wp-json\/wp\/v2\/media?parent=1781"}],"wp:term":[{"taxonomy":"linha","embeddable":true,"href":"https:\/\/ampla.ind.br\/es\/wp-json\/wp\/v2\/linha?post=1781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}